{"id":10002769,"date":"2025-10-05T13:52:20","date_gmt":"2025-10-05T17:52:20","guid":{"rendered":"https:\/\/www.abccommunity.com\/staging\/9856\/?post_type=tribe_events&#038;p=13788"},"modified":"2025-10-31T12:26:05","modified_gmt":"2025-10-31T16:26:05","slug":"church-council-meeting-3","status":"publish","type":"tribe_events","link":"https:\/\/www.abccommunity.com\/staging\/9856\/event\/church-council-meeting-3\/2026-12-07\/","title":{"rendered":"Church Council Meeting"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"template":"","meta":{"nf_dc_page":"","_EventAllDay":false,"_EventTimezone":"America\/New_York","_EventStartDate":"2026-12-07 18:00:00","_EventEndDate":"2026-12-07 18:00:00","_EventStartDateUTC":"2026-12-07 23:00:00","_EventEndDateUTC":"2026-12-07 23:00:00","_EventShowMap":false,"_EventShowMapLink":true,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"$","_EventCurrencyCode":"USD","_EventCurrencyPosition":"prefix","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"[{\"all_day\":false,\"multi_day\":false,\"type\":\"monthly\",\"limit_type\":\"date\",\"limit\":\"2026-12-07\",\"_limit_date_input\":\"December 7, 2026\",\"between\":1,\"start_time\":\"18:00:00\",\"end_time\":\"18:00:00\",\"day\":1,\"week\":\"first\"}]","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"[{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"18:00:00\",\"end_time\":\"18:00:00\",\"start_date\":\"2026-02-02\",\"_start_date_input\":\"February 2, 2026\",\"_start_time_input\":\"6:00 pm\",\"_end_time_input\":\"6:00 pm\"},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"18:00:00\",\"end_time\":\"18:00:00\",\"start_date\":\"2026-03-02\",\"_start_date_input\":\"March 2, 2026\",\"_start_time_input\":\"6:00 pm\",\"_end_time_input\":\"6:00 pm\"},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"18:00:00\",\"end_time\":\"18:00:00\",\"start_date\":\"2026-07-06\",\"_start_date_input\":\"July 6, 2026\",\"_start_time_input\":\"6:00 pm\",\"_end_time_input\":\"6:00 pm\"},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"18:00:00\",\"end_time\":\"18:00:00\",\"start_date\":\"2026-04-06\",\"_start_date_input\":\"April 6, 2026\",\"_start_time_input\":\"6:00 pm\",\"_end_time_input\":\"6:00 pm\"},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"18:00:00\",\"end_time\":\"18:00:00\",\"start_date\":\"2026-09-07\",\"_start_date_input\":\"September 7, 2026\",\"_start_time_input\":\"6:00 pm\",\"_end_time_input\":\"6:00 pm\"},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"18:00:00\",\"end_time\":\"18:00:00\",\"start_date\":\"2026-06-01\",\"_start_date_input\":\"June 1, 2026\",\"_start_time_input\":\"6:00 pm\",\"_end_time_input\":\"6:00 pm\"}]","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-10002769","tribe_events","type-tribe_events","status-publish","hentry","tribe-recurring-event","tribe-recurring-event-parent"],"_links":{"self":[{"href":"https:\/\/www.abccommunity.com\/staging\/9856\/wp-json\/wp\/v2\/tribe_events\/10002769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abccommunity.com\/staging\/9856\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.abccommunity.com\/staging\/9856\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.abccommunity.com\/staging\/9856\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.abccommunity.com\/staging\/9856\/wp-json\/wp\/v2\/tribe_events\/10002769\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.abccommunity.com\/staging\/9856\/wp-json\/wp\/v2\/media?parent=10002769"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abccommunity.com\/staging\/9856\/wp-json\/wp\/v2\/tags?post=10002769"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.abccommunity.com\/staging\/9856\/wp-json\/wp\/v2\/tribe_events_cat?post=10002769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}