{"id":10002397,"date":"2025-10-05T14:07:43","date_gmt":"2025-10-05T18:07:43","guid":{"rendered":"https:\/\/www.abccommunity.com\/staging\/9856\/?post_type=tribe_events&#038;p=13800"},"modified":"2025-12-23T14:50:49","modified_gmt":"2025-12-23T19:50:49","slug":"youth-discipleship-groups","status":"publish","type":"tribe_events","link":"https:\/\/www.abccommunity.com\/staging\/9856\/event\/youth-discipleship-groups\/2026-04-26\/","title":{"rendered":"Youth Small Groups"},"content":{"rendered":"<p>Grades 6th &#8211; 12th.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grades 6th &#8211; 12th.<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","meta":{"nf_dc_page":"","_EventAllDay":false,"_EventTimezone":"America\/New_York","_EventStartDate":"2026-04-26 17:30:00","_EventEndDate":"2026-04-26 19:00:00","_EventStartDateUTC":"2026-04-26 21:30:00","_EventEndDateUTC":"2026-04-26 23:00:00","_EventShowMap":false,"_EventShowMapLink":true,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"$","_EventCurrencyCode":"USD","_EventCurrencyPosition":"prefix","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"[{\"all_day\":false,\"multi_day\":false,\"type\":\"weekly\",\"limit_type\":\"date\",\"limit\":\"2026-04-26\",\"_limit_date_input\":\"April 26, 2026\",\"between\":1,\"start_time\":\"17:30:00\",\"end_time\":\"19:00:00\",\"days\":[7]}]","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"[{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"17:30:00\",\"end_time\":\"19:00:00\",\"start_date\":\"2026-04-05\",\"_start_date_input\":\"April 5, 2026\",\"_start_time_input\":\"5:30 pm\",\"_end_time_input\":\"7:00 pm\"},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"17:30:00\",\"end_time\":\"19:00:00\",\"start_date\":\"2026-02-01\",\"_start_date_input\":\"February 1, 2026\",\"_start_time_input\":\"5:30 pm\",\"_end_time_input\":\"7:00 pm\"},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"17:30:00\",\"end_time\":\"19:00:00\",\"start_date\":\"2026-02-08\",\"_start_date_input\":\"February 8, 2026\",\"_start_time_input\":\"5:30 pm\",\"_end_time_input\":\"7:00 pm\"},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"17:30:00\",\"end_time\":\"19:00:00\",\"start_date\":\"2026-03-15\",\"_start_date_input\":\"March 15, 2026\",\"_start_time_input\":\"5:30 pm\",\"_end_time_input\":\"7:00 pm\"},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"17:30:00\",\"end_time\":\"19:00:00\",\"start_date\":\"2026-03-22\",\"_start_date_input\":\"March 22, 2026\",\"_start_time_input\":\"5:30 pm\",\"_end_time_input\":\"7:00 pm\"},{\"all_day\":false,\"multi_day\":false,\"type\":\"single\",\"between\":1,\"start_time\":\"17:30:00\",\"end_time\":\"19:00:00\",\"start_date\":\"2026-04-12\",\"_start_date_input\":\"April 12, 2026\",\"_start_time_input\":\"5:30 pm\",\"_end_time_input\":\"7:00 pm\"}]","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-10002397","tribe_events","type-tribe_events","status-publish","hentry","tribe-recurring-event","tribe-recurring-event-parent"],"_links":{"self":[{"href":"https:\/\/www.abccommunity.com\/staging\/9856\/wp-json\/wp\/v2\/tribe_events\/10002397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abccommunity.com\/staging\/9856\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.abccommunity.com\/staging\/9856\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.abccommunity.com\/staging\/9856\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.abccommunity.com\/staging\/9856\/wp-json\/wp\/v2\/tribe_events\/10002397\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.abccommunity.com\/staging\/9856\/wp-json\/wp\/v2\/media?parent=10002397"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abccommunity.com\/staging\/9856\/wp-json\/wp\/v2\/tags?post=10002397"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.abccommunity.com\/staging\/9856\/wp-json\/wp\/v2\/tribe_events_cat?post=10002397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}